<br />
<b>Notice</b>:  Function _load_textdomain_just_in_time was called <strong>incorrectly</strong>. Translation loading for the <code>acf</code> domain was triggered too early. This is usually an indicator for some code in the plugin or theme running too early. Translations should be loaded at the <code>init</code> action or later. Please see <a href="https://developer.wordpress.org/advanced-administration/debug/debug-wordpress/">Debugging in WordPress</a> for more information. (This message was added in version 6.7.0.) in <b>/srv/www/paderborner-mischtechnik-symposium.de/wp-includes/functions.php</b> on line <b>6170</b><br />
{"id":815,"date":"2018-07-18T11:18:21","date_gmt":"2018-07-18T09:18:21","guid":{"rendered":"https:\/\/paderborner-mischtechnik-symposium.de\/?page_id=815"},"modified":"2021-02-24T14:57:20","modified_gmt":"2021-02-24T12:57:20","slug":"anmeldung","status":"publish","type":"page","link":"https:\/\/paderborner-mischtechnik-symposium.de\/en\/anmeldung\/","title":{"rendered":"Registration"},"content":{"rendered":"<div id=\"pl-815\"  class=\"panel-layout\" ><div id=\"pg-815-0\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-815-0\" ><div id=\"pgc-815-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-815-0-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-headline so-widget-sow-headline-default-725fae60071f-815\"\n\t\t\t\n\t\t><div class=\"sow-headline-container\">\n\t\t\t\t\t\t\t<h1 class=\"sow-headline\">\n\t\t\t\t\t\tRegistration for the 9th Paderborn Mixed Media Symposium DIGITAL\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t<\/div>\n<\/div><\/div><div id=\"panel-815-0-0-1\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<div id=\"panel-9-3-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child\" data-index=\"6\">\n<div class=\"so-widget-sow-headline so-widget-sow-headline-default-b302b7fc5bfe\">\n<div class=\"sow-headline-container\">\n<h4 class=\"sow-sub-headline\" style=\"text-align: center;\"><strong>Jetzt anmelden und einen der begrenzten Pl\u00e4tze sichern. Die Teilnahme ist kostenfrei.<\/strong><\/h4>\n<p style=\"text-align: center;\"><strong><span style=\"color: #ff0000;\">Anmeldeschluss ist jeweils 12 Uhr am Vortag der Veranstaltung. Aus technischen Gr\u00fcnden k\u00f6nnen wir sp\u00e4ter eintreffende Anmeldungen nicht ber\u00fccksichtigen.<\/span> <\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Bitte beachten Sie, dass nur Anmeldungen mit E-Mail-Adressen von Unternehmen und Institutionen (z.B. Universit\u00e4ten) zugelassen werden.<\/strong><br \/>\n<strong>Anmeldungen mit privaten E-Mail-Adressen k\u00f6nnen leider nicht ber\u00fccksichtigt werden.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Jetzt anmelden und einen der begrenzten Pl\u00e4tze sichern. Die Teilnahme ist kostenfrei. Anmeldeschluss ist jeweils 12 Uhr am Vortag der Veranstaltung. Aus technischen Gr\u00fcnden k\u00f6nnen wir sp\u00e4ter eintreffende Anmeldungen nicht ber\u00fccksichtigen. Bitte beachten Sie, dass nur Anmeldungen mit E-Mail-Adressen von Unternehmen und Institutionen (z.B. Universit\u00e4ten) zugelassen werden. Anmeldungen mit privaten E-Mail-Adressen k\u00f6nnen leider nicht ber\u00fccksichtigt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":738,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-eventanmeldung.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-815","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anmeldung - 9. Paderborner Mischtechnik Symposium DIGITAL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paderborner-mischtechnik-symposium.de\/en\/anmeldung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anmeldung - 9. Paderborner Mischtechnik Symposium DIGITAL\" \/>\n<meta property=\"og:description\" content=\"Jetzt anmelden und einen der begrenzten Pl\u00e4tze sichern. Die Teilnahme ist kostenfrei. Anmeldeschluss ist jeweils 12 Uhr am Vortag der Veranstaltung. Aus technischen Gr\u00fcnden k\u00f6nnen wir sp\u00e4ter eintreffende Anmeldungen nicht ber\u00fccksichtigen. Bitte beachten Sie, dass nur Anmeldungen mit E-Mail-Adressen von Unternehmen und Institutionen (z.B. Universit\u00e4ten) zugelassen werden. Anmeldungen mit privaten E-Mail-Adressen k\u00f6nnen leider nicht ber\u00fccksichtigt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paderborner-mischtechnik-symposium.de\/en\/anmeldung\/\" \/>\n<meta property=\"og:site_name\" content=\"9. Paderborner Mischtechnik Symposium DIGITAL\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-24T12:57:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paderborner-mischtechnik-symposium.de\/wp-content\/uploads\/mischtechnik-symposium.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"379\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/anmeldung\\\/\",\"url\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/anmeldung\\\/\",\"name\":\"Anmeldung - 9. Paderborner Mischtechnik Symposium DIGITAL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/anmeldung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/anmeldung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/wp-content\\\/uploads\\\/mischtechnik-symposium.jpg\",\"datePublished\":\"2018-07-18T09:18:21+00:00\",\"dateModified\":\"2021-02-24T12:57:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/anmeldung\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/anmeldung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/anmeldung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/wp-content\\\/uploads\\\/mischtechnik-symposium.jpg\",\"contentUrl\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/wp-content\\\/uploads\\\/mischtechnik-symposium.jpg\",\"width\":1500,\"height\":379},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/anmeldung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anmeldung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/#website\",\"url\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/\",\"name\":\"9. Paderborner Mischtechnik Symposium DIGITAL\",\"description\":\"9. Paderborner Mischtechnik Symposium DIGITAL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paderborner-mischtechnik-symposium.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anmeldung - 9. Paderborner Mischtechnik Symposium DIGITAL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paderborner-mischtechnik-symposium.de\/en\/anmeldung\/","og_locale":"en_US","og_type":"article","og_title":"Anmeldung - 9. Paderborner Mischtechnik Symposium DIGITAL","og_description":"Jetzt anmelden und einen der begrenzten Pl\u00e4tze sichern. Die Teilnahme ist kostenfrei. Anmeldeschluss ist jeweils 12 Uhr am Vortag der Veranstaltung. Aus technischen Gr\u00fcnden k\u00f6nnen wir sp\u00e4ter eintreffende Anmeldungen nicht ber\u00fccksichtigen. Bitte beachten Sie, dass nur Anmeldungen mit E-Mail-Adressen von Unternehmen und Institutionen (z.B. Universit\u00e4ten) zugelassen werden. Anmeldungen mit privaten E-Mail-Adressen k\u00f6nnen leider nicht ber\u00fccksichtigt [&hellip;]","og_url":"https:\/\/paderborner-mischtechnik-symposium.de\/en\/anmeldung\/","og_site_name":"9. Paderborner Mischtechnik Symposium DIGITAL","article_modified_time":"2021-02-24T12:57:20+00:00","og_image":[{"width":1500,"height":379,"url":"https:\/\/paderborner-mischtechnik-symposium.de\/wp-content\/uploads\/mischtechnik-symposium.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paderborner-mischtechnik-symposium.de\/anmeldung\/","url":"https:\/\/paderborner-mischtechnik-symposium.de\/anmeldung\/","name":"Anmeldung - 9. Paderborner Mischtechnik Symposium DIGITAL","isPartOf":{"@id":"https:\/\/paderborner-mischtechnik-symposium.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paderborner-mischtechnik-symposium.de\/anmeldung\/#primaryimage"},"image":{"@id":"https:\/\/paderborner-mischtechnik-symposium.de\/anmeldung\/#primaryimage"},"thumbnailUrl":"https:\/\/paderborner-mischtechnik-symposium.de\/wp-content\/uploads\/mischtechnik-symposium.jpg","datePublished":"2018-07-18T09:18:21+00:00","dateModified":"2021-02-24T12:57:20+00:00","breadcrumb":{"@id":"https:\/\/paderborner-mischtechnik-symposium.de\/anmeldung\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paderborner-mischtechnik-symposium.de\/anmeldung\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/paderborner-mischtechnik-symposium.de\/anmeldung\/#primaryimage","url":"https:\/\/paderborner-mischtechnik-symposium.de\/wp-content\/uploads\/mischtechnik-symposium.jpg","contentUrl":"https:\/\/paderborner-mischtechnik-symposium.de\/wp-content\/uploads\/mischtechnik-symposium.jpg","width":1500,"height":379},{"@type":"BreadcrumbList","@id":"https:\/\/paderborner-mischtechnik-symposium.de\/anmeldung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paderborner-mischtechnik-symposium.de\/"},{"@type":"ListItem","position":2,"name":"Anmeldung"}]},{"@type":"WebSite","@id":"https:\/\/paderborner-mischtechnik-symposium.de\/#website","url":"https:\/\/paderborner-mischtechnik-symposium.de\/","name":"9. Paderborner Mischtechnik Symposium DIGITAL","description":"9. Paderborner Mischtechnik Symposium DIGITAL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paderborner-mischtechnik-symposium.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/paderborner-mischtechnik-symposium.de\/en\/wp-json\/wp\/v2\/pages\/815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paderborner-mischtechnik-symposium.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/paderborner-mischtechnik-symposium.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/paderborner-mischtechnik-symposium.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paderborner-mischtechnik-symposium.de\/en\/wp-json\/wp\/v2\/comments?post=815"}],"version-history":[{"count":28,"href":"https:\/\/paderborner-mischtechnik-symposium.de\/en\/wp-json\/wp\/v2\/pages\/815\/revisions"}],"predecessor-version":[{"id":1809,"href":"https:\/\/paderborner-mischtechnik-symposium.de\/en\/wp-json\/wp\/v2\/pages\/815\/revisions\/1809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paderborner-mischtechnik-symposium.de\/en\/wp-json\/wp\/v2\/media\/738"}],"wp:attachment":[{"href":"https:\/\/paderborner-mischtechnik-symposium.de\/en\/wp-json\/wp\/v2\/media?parent=815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}